{"id":83,"date":"2014-08-03T16:51:00","date_gmt":"2014-08-03T16:51:00","guid":{"rendered":"http:\/\/localhost:97\/wp-beuh\/?page_id=83"},"modified":"2014-08-03T16:51:00","modified_gmt":"2014-08-03T16:51:00","slug":"blog-sidebar","status":"publish","type":"page","link":"http:\/\/theme.ridianur.com\/beuh\/blog-sidebar\/","title":{"rendered":"Blog Sidebar"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"open","template":"blog-sidebar.php","meta":[],"_links":{"self":[{"href":"http:\/\/theme.ridianur.com\/beuh\/wp-json\/wp\/v2\/pages\/83"}],"collection":[{"href":"http:\/\/theme.ridianur.com\/beuh\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/theme.ridianur.com\/beuh\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/theme.ridianur.com\/beuh\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/theme.ridianur.com\/beuh\/wp-json\/wp\/v2\/comments?post=83"}],"version-history":[{"count":0,"href":"http:\/\/theme.ridianur.com\/beuh\/wp-json\/wp\/v2\/pages\/83\/revisions"}],"wp:attachment":[{"href":"http:\/\/theme.ridianur.com\/beuh\/wp-json\/wp\/v2\/media?parent=83"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}